{"id":6442,"date":"2024-11-19T15:50:04","date_gmt":"2024-11-19T13:50:04","guid":{"rendered":"https:\/\/drap-art.org\/?p=6442"},"modified":"2024-11-20T21:14:52","modified_gmt":"2024-11-20T19:14:52","slug":"empieza-el-28o-festival-internacional-de-arte-sostenible","status":"publish","type":"post","link":"https:\/\/drap-art.org\/es\/noticias\/empieza-el-28o-festival-internacional-de-arte-sostenible\/","title":{"rendered":"Empieza el 28\u00ba Festival de Arte Sostenible de Catalu\u00f1a"},"content":{"rendered":"<p>El Festival Drap-Art vuelve a Barcelona! Durante un mes, el Barrio G\u00f3tico se convertir\u00e1 en el epicentro del arte y la sostenibilidad con exposiciones, actividades gratuitas y acciones culturales en espacios p\u00fablicos, galer\u00edas y edificios emblem\u00e1ticos.<\/p>\n<p>En esta 28.\u00aa edici\u00f3n, el festival re\u00fane 60 artistas con m\u00e1s de 100 obras hechas a partir de objetos recuperados, transmitiendo emociones y mensajes que invitan a la reflexi\u00f3n.<\/p>\n<p>Este a\u00f1o, Drap-Art aborda los retos sociales, ideol\u00f3gicos y pol\u00edticos actuales desde el activismo art\u00edstico, reivindicando un retorno a los valores humanistas como clave para conseguir una sostenibilidad global. No te lo pierdas!<\/p>\n<p><a class=\"el-content uk-button uk-button-secondary uk-button-small uk-flex-inline uk-flex-center uk-flex-middle\" href=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/drap-art-2024-programa-esp.pdf\"><br \/>\n        <span class=\"uk-margin-small-right uk-icon\" uk-icon=\"download\"><svg width=\"20\" height=\"20\" viewBox=\"0 0 20 20\"><polyline fill=\"none\" stroke=\"#000\" points=\"14,10 9.5,14.5 5,10\"><\/polyline><rect x=\"3\" y=\"17\" width=\"13\" height=\"1\"><\/rect><line fill=\"none\" stroke=\"#000\" x1=\"9.5\" y1=\"13.91\" x2=\"9.5\" y2=\"3\"><\/line><\/svg><\/span><br \/>\n        Programa Drap-Art&#8217;24    <\/p>\n<p><\/a><\/p>\n<h4>Esta semana destacamos&#8230;<\/h4>\n<figure id=\"attachment_6461\" aria-describedby=\"caption-attachment-6461\" style=\"width: 1440px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6461\" src=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Maria-Salouvardou-1-sm.jpg\" alt=\"\" width=\"1440\" height=\"957\" srcset=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Maria-Salouvardou-1-sm.jpg 1440w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Maria-Salouvardou-1-sm-450x299.jpg 450w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Maria-Salouvardou-1-sm-600x399.jpg 600w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Maria-Salouvardou-1-sm-1320x877.jpg 1320w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><figcaption id=\"caption-attachment-6461\" class=\"wp-caption-text\">Maria Salouvardou \u00b7 Performance Dead Land<\/figcaption><\/figure>\n<h3>Performance &#8211; Maria Salouvardou<\/h3>\n<p><strong>Jueves 21 de noviembre, Calle Ciudad, 3 &#8211; 19:00 h, Dead Land<\/strong><\/p>\n<p>Maria transforma objetos reciclados en piezas \u00fanicas, combinando m\u00fasica, texto y video. Su performance explora el arte como medio para dar nueva vida a aquello olvidado, con un enfoque creativo y sostenible.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_6449\" aria-describedby=\"caption-attachment-6449\" style=\"width: 1440px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6449\" src=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/basuringo-bottom2-sm.jpg\" alt=\"\" width=\"1440\" height=\"989\" srcset=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/basuringo-bottom2-sm.jpg 1440w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/basuringo-bottom2-sm-450x309.jpg 450w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/basuringo-bottom2-sm-600x412.jpg 600w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/basuringo-bottom2-sm-1320x907.jpg 1320w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><figcaption id=\"caption-attachment-6449\" class=\"wp-caption-text\">Basuringo by Twisted Fairground<\/figcaption><\/figure>\n<h3>Ruta de expos con Basuringo<\/h3>\n<p><strong>Jueves 21 de noviembre, Calle Ciudad, 3 &#8211; 20:00 h<\/strong><\/p>\n<p>Una performance presentada por Twisted Fairground. Mezcla instalaci\u00f3n art\u00edstica, t\u00edteres rob\u00f3ticas y teatro para explorar el mundo del \u00abdesechable\u00bb y su conexi\u00f3n con la humanidad. Una experiencia \u00fanica y transformadora.<\/p>\n<p><strong>Ruta de exposiciones: <\/strong>Todos los s\u00e1bados, de 12 h a 14 h<\/p>\n<p>Acomp\u00e1\u00f1anos en un recorrido por los espacios del Festival Drap-Art, descubre 9 rutas guiadas de exposiciones distribuidas por el Barrio G\u00f3tico.<\/p>\n<p>&nbsp;<\/p>\n<h4>Conciertos inaugurales<\/h4>\n<figure id=\"attachment_6452\" aria-describedby=\"caption-attachment-6452\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6452\" src=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/DJ-Miskovic-sm.jpg\" alt=\"\" width=\"960\" height=\"1440\" srcset=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/DJ-Miskovic-sm.jpg 960w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/DJ-Miskovic-sm-450x675.jpg 450w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/DJ-Miskovic-sm-600x900.jpg 600w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/DJ-Miskovic-sm-300x450.jpg 300w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption id=\"caption-attachment-6452\" class=\"wp-caption-text\">DJ Miskovic<\/figcaption><\/figure>\n<h3>DJ MISKOVIC<\/h3>\n<p><strong>S\u00e1bado 23 de noviembre, de 18 h a 19 h, en la Pla\u00e7a del Rei<\/strong><\/p>\n<p>Miskovic, nacida en Barcelona y con ra\u00edces argentinas, es una fot\u00f3grafa y DJ apasionada que combina ritmos como el afro house, el techno mel\u00f3dico y el indie dance. Despu\u00e9s de a\u00f1os capturando los mejores DJs del mundo en festivales como Brunch Barcelona, Off Sonar e Hivernacle, ahora brilla detr\u00e1s de los platos, llevando su amor por la m\u00fasica a otro nivel.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_6458\" aria-describedby=\"caption-attachment-6458\" style=\"width: 1018px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6458\" src=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/la-maga-sm.png\" alt=\"\" width=\"1018\" height=\"1440\" srcset=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/la-maga-sm.png 1018w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/la-maga-sm-450x637.png 450w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/la-maga-sm-600x849.png 600w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/la-maga-sm-318x450.png 318w\" sizes=\"(max-width: 1018px) 100vw, 1018px\" \/><figcaption id=\"caption-attachment-6458\" class=\"wp-caption-text\">La Maga<\/figcaption><\/figure>\n<h3>LA MAGA (LIVE SHOW)<\/h3>\n<p><strong>S\u00e1bado 23 de noviembre, de 19 h a 20:15 h, a la Pla\u00e7a del Rei<\/strong><\/p>\n<p>La Maga es una rapera argentina que fusiona rap con ritmos latinoamericanos y sonidos electr\u00f3nicos, creando una experiencia \u00fanica donde pasado y futuro se encuentran. Con la percusionista Gala Celia, Mat\u00edas Herrera y el productor Vitu Valera.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_6446\" aria-describedby=\"caption-attachment-6446\" style=\"width: 948px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6446\" src=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Adelaida-by-Bo-Bannink-sm.jpg\" alt=\"\" width=\"948\" height=\"1440\" srcset=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Adelaida-by-Bo-Bannink-sm.jpg 948w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Adelaida-by-Bo-Bannink-sm-450x684.jpg 450w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Adelaida-by-Bo-Bannink-sm-600x911.jpg 600w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Adelaida-by-Bo-Bannink-sm-296x450.jpg 296w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><figcaption id=\"caption-attachment-6446\" class=\"wp-caption-text\">Adelaida \u00b7 Photo by Bo Bannink<\/figcaption><\/figure>\n<h3>ADELAIDA (LIVE SHOW)<\/h3>\n<p><strong>S\u00e1bado 23 de noviembre, de 20:25 h a 21:45 h, en Pla\u00e7a del Rei<\/strong><\/p>\n<p>La cantautora y productora catalana Adelaida explora la voz como expresi\u00f3n ritual, combinando ambiente coral y electr\u00f3nica oscura. Su segundo \u00e1lbum, Mu\u00e9rdago, estrenado a S\u00f3nar 2024, es un viaje sonoro lleno de emoci\u00f3n que consolida su presencia en la escena musical.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_6464\" aria-describedby=\"caption-attachment-6464\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6464\" src=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/veacks-05-sm.jpg\" alt=\"\" width=\"960\" height=\"1440\" srcset=\"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/veacks-05-sm.jpg 960w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/veacks-05-sm-450x675.jpg 450w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/veacks-05-sm-600x900.jpg 600w, https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/veacks-05-sm-300x450.jpg 300w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><figcaption id=\"caption-attachment-6464\" class=\"wp-caption-text\">Veacks<\/figcaption><\/figure>\n<h3>VEACKS (DJ)<\/h3>\n<p><strong>S\u00e1bado 23 de noviembre, de 21:45 h a 23 h, en la Pla\u00e7a del Rei<\/strong><\/p>\n<p>Veacks, DJ suizo-franc\u00e9s con sede en Barcelona, fusiona ritmos latinos y afro para crear sets vibrantes y din\u00e1micos. Con una selecci\u00f3n aut\u00e9ntica de Afrobeat, salsa y cumbia, crea atm\u00f3sferas irresistibles que celebran la danza y el pulso global.<\/p>\n<p>&nbsp;<\/p>\n<h4>Festival Drap-Art<\/h4>\n<p>Una experiencia \u00fanica llena de exposiciones, instalaciones art\u00edsticas, actividades gratuitas y mucho m\u00e1s. Conoce los artistas, descubre el poder del reciclaje creativo y disfruta de un mes de cultura en el coraz\u00f3n del Barrio G\u00f3tico.<\/p>\n<p>Para mayor informaci\u00f3n sobre horarios, rutas y actividades, visita la nuestro web. Te esperamos!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Festival Drap-Art vuelve a Barcelona! Durante un mes, el Barrio G\u00f3tico se convertir\u00e1 en el epicentro del arte y la sostenibilidad con exposiciones, actividades gratuitas y acciones culturales en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[],"class_list":["post-6442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empieza el 28\u00ba Festival de Arte Sostenible de Catalu\u00f1a - Drap-Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"german\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empieza el 28\u00ba Festival de Arte Sostenible de Catalu\u00f1a - Drap-Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/","twitter_misc":{"Escrito por":"german","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/#article","isPartOf":{"@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/"},"author":{"name":"german","@id":"https:\/\/drap-art.org\/#\/schema\/person\/b7f8fa9112d1008810fff78f5ec09cf2"},"headline":"Empieza el 28\u00ba Festival de Arte Sostenible de Catalu\u00f1a","datePublished":"2024-11-19T13:50:04+00:00","dateModified":"2024-11-20T19:14:52+00:00","mainEntityOfPage":{"@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/"},"wordCount":634,"publisher":{"@id":"https:\/\/drap-art.org\/#organization"},"image":{"@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Maria-Salouvardou-2-sm.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/","url":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/","name":"Empieza el 28\u00ba Festival de Arte Sostenible de Catalu\u00f1a - Drap-Art","isPartOf":{"@id":"https:\/\/drap-art.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/#primaryimage"},"image":{"@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Maria-Salouvardou-2-sm.jpg","datePublished":"2024-11-19T13:50:04+00:00","dateModified":"2024-11-20T19:14:52+00:00","breadcrumb":{"@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/#primaryimage","url":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Maria-Salouvardou-2-sm.jpg","contentUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/11\/Maria-Salouvardou-2-sm.jpg","width":1440,"height":982},{"@type":"BreadcrumbList","@id":"https:\/\/drap-art.org\/noticies\/comenca-el-28e-festival-internacional-dart-sostenible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drap-art.org\/es\/"},{"@type":"ListItem","position":2,"name":"Empieza el 28\u00ba Festival de Arte Sostenible de Catalu\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/drap-art.org\/#website","url":"https:\/\/drap-art.org\/","name":"Drap-Art","description":"Festival Internacional de Arte y Sostenibilidad","publisher":{"@id":"https:\/\/drap-art.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drap-art.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drap-art.org\/#organization","name":"Associaci\u00f3 Drap-Art","url":"https:\/\/drap-art.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drap-art.org\/#\/schema\/logo\/image\/","url":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/10\/logo-drapart-24.png","contentUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/10\/logo-drapart-24.png","width":2157,"height":1929,"caption":"Associaci\u00f3 Drap-Art"},"image":{"@id":"https:\/\/drap-art.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/drapart\/","https:\/\/x.com\/DrapArt","https:\/\/www.instagram.com\/drapart_org\/","https:\/\/www.youtube.com\/channel\/UC_FGj-k0m_HgMv_aYSN5_4Q"]},{"@type":"Person","@id":"https:\/\/drap-art.org\/#\/schema\/person\/b7f8fa9112d1008810fff78f5ec09cf2","name":"german","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/436d13c83f158ff3489fddbbac857baa2dc00f85c1d04102eb0a8d6d7acc8ef5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/436d13c83f158ff3489fddbbac857baa2dc00f85c1d04102eb0a8d6d7acc8ef5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/436d13c83f158ff3489fddbbac857baa2dc00f85c1d04102eb0a8d6d7acc8ef5?s=96&d=mm&r=g","caption":"german"},"sameAs":["https:\/\/drap-art.org"],"url":"https:\/\/drap-art.org\/es\/author\/german\/"}]}},"_links":{"self":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/posts\/6442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/comments?post=6442"}],"version-history":[{"count":0,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/posts\/6442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/media\/6457"}],"wp:attachment":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/media?parent=6442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/categories?post=6442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/tags?post=6442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}