{"id":9725,"date":"2025-04-30T13:24:56","date_gmt":"2025-04-30T11:24:56","guid":{"rendered":"https:\/\/drap-art.org\/?post_type=projectes&#038;p=9725"},"modified":"2026-04-17T19:04:13","modified_gmt":"2026-04-17T17:04:13","slug":"tardor-dart-2025","status":"publish","type":"projectes","link":"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/","title":{"rendered":"Tardor d&#8217;Art 2025"},"content":{"rendered":"<h1 class=\"uk-margin-remove-bottom\">Tardor d&#8217;Art 2025<\/h1>\n<h2 class=\"uk-margin-remove-top\">Feria de Arte de Formentera de artistas independientes<\/h2>\n<p><strong>Del 5 al 11 de octubre de 2025 en la Sala de Exposiciones \u00abAjuntament Vell\u00bb, Centre Antoni Tur \u00abGabrielet\u00bb y Jard\u00ed de Ses Eres.<\/strong><\/p>\n<p>Estamos muy contentos de anunciar la cuarta edici\u00f3n de la Tardor d\u2019Art, una cita anual que transforma Formentera en un espacio de expresi\u00f3n art\u00edstica libre, reflexiva y experimental.<\/p>\n<p>La Tardor d&#8217;Art naci\u00f3 en 2022 impulsada por la Asociaci\u00f3n de Artistas de Formentera (AdAF), con el apoyo del Consell Insular de Formentera y de otras entidades culturales de la isla. A\u00f1o tras a\u00f1o, hemos consolidado una plataforma donde artistas residentes y visitantes pueden mostrar su trabajo m\u00e1s personal, sin estar condicionados por criterios comerciales, pero con la opci\u00f3n real de dar salida a sus obras.<\/p>\n<p>En un mundo marcado por la saturaci\u00f3n tur\u00edstica y la crisis clim\u00e1tica, las Islas Baleares necesitan m\u00e1s que nunca de su masa cr\u00edtica de artistas para abrir nuevos debates e imaginar futuros posibles. La Tardor d&#8217;Art quiere ser este espacio de encuentro, intercambio e inspiraci\u00f3n.<\/p>\n<p>En 2025, la exposici\u00f3n se desplegar\u00e1 en tres espacios emblem\u00e1ticos de Sant Francesc: la Sala de Exposiciones \u00abAjuntament Vell\u00bb, el Centre Antoni Tur \u00abGabrielet\u00bb y el Jard\u00ed de Ses Eres, que acoger\u00e1 intervenciones escult\u00f3ricas, performances, videomapping, m\u00fasica en directo y proyecciones audiovisuales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1600\" class=\"aligncenter size-full wp-image-11531\" src=\"https:\/\/drap-art.org\/wp-content\/uploads\/2025\/04\/tardor25.jpg\" alt=\"Tardor d'Art Formentera\" srcset=\"https:\/\/drap-art.org\/wp-content\/uploads\/2025\/04\/tardor25.jpg 1130w, https:\/\/drap-art.org\/wp-content\/uploads\/2025\/04\/tardor25-318x450.jpg 318w, https:\/\/drap-art.org\/wp-content\/uploads\/2025\/04\/tardor25-450x637.jpg 450w, https:\/\/drap-art.org\/wp-content\/uploads\/2025\/04\/tardor25-600x850.jpg 600w\" sizes=\"(max-width: 1130px) 100vw, 1130px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tardor d&#8217;Art 2025 Feria de Arte de Formentera de artistas independientes Del 5 al 11 de octubre de 2025 en la Sala de Exposiciones \u00abAjuntament Vell\u00bb, Centre Antoni Tur \u00abGabrielet\u00bb [&hellip;]<\/p>\n","protected":false},"featured_media":9737,"template":"","format":"standard","tipus":[],"class_list":["post-9725","projectes","type-projectes","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tardor d&#039;Art 2025 | Arte contempor\u00e1neo en Formentera<\/title>\n<meta name=\"description\" content=\"Del 2 al 11 de octubre de 2025, Formentera celebra la 4\u00aa edici\u00f3n de Tardor d&#039;Art: exposiciones, performances y arte p\u00fablico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tardor d'Art 2025 | Arte contempor\u00e1neo en Formentera","description":"Del 2 al 11 de octubre de 2025, Formentera celebra la 4\u00aa edici\u00f3n de Tardor d'Art: exposiciones, performances y arte p\u00fablico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/","url":"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/","name":"Tardor d'Art 2025 | Arte contempor\u00e1neo en Formentera","isPartOf":{"@id":"https:\/\/drap-art.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/#primaryimage"},"image":{"@id":"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2025\/04\/Inauguracio_8-6d436f5b.webp","datePublished":"2025-04-30T11:24:56+00:00","dateModified":"2026-04-17T17:04:13+00:00","description":"Del 2 al 11 de octubre de 2025, Formentera celebra la 4\u00aa edici\u00f3n de Tardor d'Art: exposiciones, performances y arte p\u00fablico.","breadcrumb":{"@id":"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/#primaryimage","url":"https:\/\/drap-art.org\/wp-content\/uploads\/2025\/04\/Inauguracio_8-6d436f5b.webp","contentUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2025\/04\/Inauguracio_8-6d436f5b.webp","width":1616,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/drap-art.org\/es\/projectes\/tardor-dart-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drap-art.org\/es\/"},{"@type":"ListItem","position":2,"name":"Tardor d&#8217;Art 2025"}]},{"@type":"WebSite","@id":"https:\/\/drap-art.org\/#website","url":"https:\/\/drap-art.org\/","name":"Drap-Art","description":"Festival Internacional de Arte y Sostenibilidad","publisher":{"@id":"https:\/\/drap-art.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drap-art.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drap-art.org\/#organization","name":"Associaci\u00f3 Drap-Art","url":"https:\/\/drap-art.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drap-art.org\/#\/schema\/logo\/image\/","url":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/10\/logo-drapart-24.png","contentUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/10\/logo-drapart-24.png","width":2157,"height":1929,"caption":"Associaci\u00f3 Drap-Art"},"image":{"@id":"https:\/\/drap-art.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/drapart\/","https:\/\/x.com\/DrapArt","https:\/\/www.instagram.com\/drapart_org\/","https:\/\/www.youtube.com\/channel\/UC_FGj-k0m_HgMv_aYSN5_4Q"]}]}},"_links":{"self":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/projectes\/9725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/projectes"}],"about":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/types\/projectes"}],"version-history":[{"count":4,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/projectes\/9725\/revisions"}],"predecessor-version":[{"id":12414,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/projectes\/9725\/revisions\/12414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/media\/9737"}],"wp:attachment":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/media?parent=9725"}],"wp:term":[{"taxonomy":"tipus","embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/tipus?post=9725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}