{"id":5555,"date":"2024-06-11T14:06:33","date_gmt":"2024-06-11T12:06:33","guid":{"rendered":"https:\/\/drap-art.org\/talent\/%ambit%\/manel-sellares\/"},"modified":"2025-02-20T15:11:14","modified_gmt":"2025-02-20T13:11:14","slug":"manel-sellares","status":"publish","type":"talent","link":"https:\/\/drap-art.org\/es\/talent\/artist-es\/manel-sellares\/","title":{"rendered":"Manel Sellar\u00e8s"},"content":{"rendered":"<p data-start=\"1161\" data-end=\"1475\">Sellar\u00e8s comenz\u00f3 a pintar cuando estaba en la escuela primaria. Realiz\u00f3 estudios de m\u00fasica (solfeo, piano y guitarra) y de arte en la Escuela de Artes Aplicadas de Terrassa, que entonces depend\u00eda de La Llotja. Es miembro de la Asociaci\u00f3n Cultural Amigos de las Artes y del Club de Ajedrez de Terrassa.<\/p>\n<p data-start=\"1477\" data-end=\"1735\">Se inclin\u00f3 m\u00e1s por la pr\u00e1ctica que por los estudios, y en lugar de ingresar en la Facultad de Bellas Artes de la Universidad de Barcelona, despu\u00e9s de superar las pruebas de acceso, form\u00f3 el grupo de m\u00fasica experimental Belmondo y decidi\u00f3 viajar a Nueva York.<\/p>\n<p data-start=\"1737\" data-end=\"2004\">A lo largo de su trayectoria ha encontrado artistas que han contribuido a su desarrollo, tanto personal como art\u00edstico, como Eloi Rocamora, Antoni Padr\u00f3s, Richard Hamilton, Francesca Llopis, Nazario, Perico Pastor, Eugeni Bonet, Toni Riera, Carlos Pazos, entre otros.<\/p>\n<p data-start=\"2006\" data-end=\"2325\" data-is-last-node=\"\" data-is-only-node=\"\">Ha expuesto en la Sala Par\u00e9s, en la Galer\u00eda A Punt de Badalona, en la Galer\u00eda H\u2082O y en la Chez Xefo Art Gallery, entre otras. Tambi\u00e9n ha expuesto en museos como la Fundaci\u00f3n Joan Mir\u00f3, el Museo de Badalona y la Sala Municipal Soler Palet de Terrassa. Adem\u00e1s, la Fundaci\u00f3n del Banco Sabadell le ha comprado varias obras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sellar\u00e8s comenz\u00f3 a pintar cuando estaba en la escuela primaria. Realiz\u00f3 estudios de m\u00fasica (solfeo, piano y guitarra) y de arte en la Escuela de Artes Aplicadas de Terrassa, que [&hellip;]<\/p>\n","protected":false},"featured_media":1292,"template":"","ambit":[431],"etiqueta":[],"class_list":["post-5555","talent","type-talent","status-publish","has-post-thumbnail","hentry","ambit-artist-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manel Sellar\u00e8s - Drap-Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manel Sellar\u00e8s - Drap-Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/","url":"https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/","name":"Manel Sellar\u00e8s - Drap-Art","isPartOf":{"@id":"https:\/\/drap-art.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/#primaryimage"},"image":{"@id":"https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/#primaryimage"},"thumbnailUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/06\/ManelSellares_2.jpg-1.jpeg","datePublished":"2024-06-11T12:06:33+00:00","dateModified":"2025-02-20T13:11:14+00:00","breadcrumb":{"@id":"https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/#primaryimage","url":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/06\/ManelSellares_2.jpg-1.jpeg","contentUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/06\/ManelSellares_2.jpg-1.jpeg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/drap-art.org\/es\/talent\/artista-drap-art\/manel-sellares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drap-art.org\/es\/"},{"@type":"ListItem","position":2,"name":"Talents","item":"https:\/\/drap-art.org\/es\/talent\/"},{"@type":"ListItem","position":3,"name":"Manel Sellar\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/drap-art.org\/#website","url":"https:\/\/drap-art.org\/","name":"Drap-Art","description":"Festival Internacional de Arte y Sostenibilidad","publisher":{"@id":"https:\/\/drap-art.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drap-art.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drap-art.org\/#organization","name":"Associaci\u00f3 Drap-Art","url":"https:\/\/drap-art.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drap-art.org\/#\/schema\/logo\/image\/","url":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/10\/logo-drapart-24.png","contentUrl":"https:\/\/drap-art.org\/wp-content\/uploads\/2024\/10\/logo-drapart-24.png","width":2157,"height":1929,"caption":"Associaci\u00f3 Drap-Art"},"image":{"@id":"https:\/\/drap-art.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/drapart\/","https:\/\/x.com\/DrapArt","https:\/\/www.instagram.com\/drapart_org\/","https:\/\/www.youtube.com\/channel\/UC_FGj-k0m_HgMv_aYSN5_4Q"]}]}},"_links":{"self":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/talent\/5555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/talent"}],"about":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/types\/talent"}],"version-history":[{"count":0,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/talent\/5555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/media\/1292"}],"wp:attachment":[{"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/media?parent=5555"}],"wp:term":[{"taxonomy":"ambit","embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/ambit?post=5555"},{"taxonomy":"etiqueta","embeddable":true,"href":"https:\/\/drap-art.org\/es\/wp-json\/wp\/v2\/etiqueta?post=5555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}